{"id":100007,"count":1,"description":"","link":"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/","name":"Akasa Air unilateral cancellation of flight tickets","slug":"akasa-air-unilateral-cancellation-of-flight-tickets","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Akasa Air unilateral cancellation of flight tickets Archives | SCC Times<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Akasa Air unilateral cancellation of flight tickets Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/\" \/>\n<meta property=\"og:site_name\" content=\"SCC Times\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/tag\\\/akasa-air-unilateral-cancellation-of-flight-tickets\\\/\",\"url\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/tag\\\/akasa-air-unilateral-cancellation-of-flight-tickets\\\/\",\"name\":\"Akasa Air unilateral cancellation of flight tickets Archives | SCC Times\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/tag\\\/akasa-air-unilateral-cancellation-of-flight-tickets\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/tag\\\/akasa-air-unilateral-cancellation-of-flight-tickets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Akasa Air unilateral cancellation of flight tickets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/\",\"name\":\"SCC Times\",\"description\":\"Bringing you the Best Analytical Legal News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Akasa Air unilateral cancellation of flight tickets Archives | SCC Times","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/","og_locale":"en_US","og_type":"article","og_title":"Akasa Air unilateral cancellation of flight tickets Archives","og_url":"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/","og_site_name":"SCC Times","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/","url":"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/","name":"Akasa Air unilateral cancellation of flight tickets Archives | SCC Times","isPartOf":{"@id":"https:\/\/www.scconline.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scconline.com\/blog\/post\/tag\/akasa-air-unilateral-cancellation-of-flight-tickets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scconline.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Akasa Air unilateral cancellation of flight tickets"}]},{"@type":"WebSite","@id":"https:\/\/www.scconline.com\/blog\/#website","url":"https:\/\/www.scconline.com\/blog\/","name":"SCC Times","description":"Bringing you the Best Analytical Legal News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scconline.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/tags\/100007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/posts?tags=100007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}