{"id":227554,"date":"2020-03-25T20:26:26","date_gmt":"2020-03-25T14:56:26","guid":{"rendered":"https:\/\/www.scconline.com\/blog\/?p=227554"},"modified":"2020-04-01T19:37:12","modified_gmt":"2020-04-01T14:07:12","slug":"covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act","status":"publish","type":"post","link":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/","title":{"rendered":"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act"},"content":{"rendered":"<p style=\"text-align: justify;\">Ministry of Home Affairs (MHA) has issued an addendum to the guidelines to all Ministries\/Departments issued yesterday (<a href=\"https:\/\/pib.gov.in\/PressReleseDetail.aspx?PRID=1607997\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/pib.gov.in\/PressReleseDetail.aspx?PRID=1607997<\/a>), regarding the Nationwide lockdown to fight Corona Virus.<\/p>\n<p style=\"text-align: justify;\">This addendum lays down additional categories of essential goods and services exempted under the Disaster Management Act, with respect to the 21- day lockdown.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/164.100.117.97\/WriteReadData\/userfiles\/Guidelines%20-%20Copy%202.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Original Guidelines Document<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/164.100.117.97\/WriteReadData\/userfiles\/Addendum%20to%20Guidelines%20Dated%2024.3.2020.pdf.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Addendum to the Guidelines<\/strong><\/a><\/p>\n<hr \/>\n<p><strong>Ministry of Home Affairs<\/strong><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #008000;\">[Press Release dt. 25-03-2020]<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #008000;\">[Source: PIB]<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ministry of Home Affairs (MHA) has issued an addendum to the guidelines to all Ministries\/Departments issued yesterday (https:\/\/pib.gov.in\/PressReleseDetail.aspx?PRID=1607997), regarding the Nationwide lockdown <\/p>\n","protected":false},"author":8808,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1188,2],"tags":[40012,39924,40216,40214,40215],"class_list":["post-227554","post","type-post","status-publish","format-standard","hentry","category-hot_off_the_press","category-news","tag-corona-virus","tag-covid-19","tag-disaster-management-act","tag-essential-goods-and-services","tag-nationwide-lockdown"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act | SCC Times<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act\" \/>\n<meta property=\"og:description\" content=\"Ministry of Home Affairs (MHA) has issued an addendum to the guidelines to all Ministries\/Departments issued yesterday (https:\/\/pib.gov.in\/PressReleseDetail.aspx?PRID=1607997), regarding the Nationwide lockdown\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/\" \/>\n<meta property=\"og:site_name\" content=\"SCC Times\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scc.online\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-25T14:56:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-01T14:07:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scconline.com\/blog\/wp-content\/uploads\/2019\/02\/Ministry-of-Home-Affairs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1330\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bhumika Indulia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bhumika Indulia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/\"},\"author\":{\"name\":\"Bhumika Indulia\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/#\\\/schema\\\/person\\\/919ec47cc1b871b362af05740398033a\"},\"headline\":\"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act\",\"datePublished\":\"2020-03-25T14:56:26+00:00\",\"dateModified\":\"2020-04-01T14:07:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/\"},\"wordCount\":90,\"commentCount\":0,\"keywords\":[\"Corona Virus\",\"COVID-19\",\"Disaster Management Act\",\"Essential Goods and Services\",\"Nationwide lockdown\"],\"articleSection\":[\"Hot Off The Press\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/\",\"url\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/\",\"name\":\"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act | SCC Times\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/#website\"},\"datePublished\":\"2020-03-25T14:56:26+00:00\",\"dateModified\":\"2020-04-01T14:07:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/#\\\/schema\\\/person\\\/919ec47cc1b871b362af05740398033a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/2020\\\/03\\\/25\\\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/\",\"name\":\"SCC Times\",\"description\":\"Bringing you the Best Analytical Legal News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/#\\\/schema\\\/person\\\/919ec47cc1b871b362af05740398033a\",\"name\":\"Bhumika Indulia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84c1b51748d0297cf12e5a898eccb7bd3eb5f0ab4ae8e275e2e65c4c83f84740?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84c1b51748d0297cf12e5a898eccb7bd3eb5f0ab4ae8e275e2e65c4c83f84740?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84c1b51748d0297cf12e5a898eccb7bd3eb5f0ab4ae8e275e2e65c4c83f84740?s=96&d=mm&r=g\",\"caption\":\"Bhumika Indulia\"},\"url\":\"https:\\\/\\\/www.scconline.com\\\/blog\\\/post\\\/author\\\/editor_1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act | SCC Times","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/","og_locale":"en_US","og_type":"article","og_title":"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act","og_description":"Ministry of Home Affairs (MHA) has issued an addendum to the guidelines to all Ministries\/Departments issued yesterday (https:\/\/pib.gov.in\/PressReleseDetail.aspx?PRID=1607997), regarding the Nationwide lockdown","og_url":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/","og_site_name":"SCC Times","article_publisher":"https:\/\/www.facebook.com\/scc.online\/","article_published_time":"2020-03-25T14:56:26+00:00","article_modified_time":"2020-04-01T14:07:12+00:00","og_image":[{"width":1330,"height":887,"url":"https:\/\/www.scconline.com\/blog\/wp-content\/uploads\/2019\/02\/Ministry-of-Home-Affairs.jpg","type":"image\/jpeg"}],"author":"Bhumika Indulia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bhumika Indulia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/#article","isPartOf":{"@id":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/"},"author":{"name":"Bhumika Indulia","@id":"https:\/\/www.scconline.com\/blog\/#\/schema\/person\/919ec47cc1b871b362af05740398033a"},"headline":"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act","datePublished":"2020-03-25T14:56:26+00:00","dateModified":"2020-04-01T14:07:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/"},"wordCount":90,"commentCount":0,"keywords":["Corona Virus","COVID-19","Disaster Management Act","Essential Goods and Services","Nationwide lockdown"],"articleSection":["Hot Off The Press","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/","url":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/","name":"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act | SCC Times","isPartOf":{"@id":"https:\/\/www.scconline.com\/blog\/#website"},"datePublished":"2020-03-25T14:56:26+00:00","dateModified":"2020-04-01T14:07:12+00:00","author":{"@id":"https:\/\/www.scconline.com\/blog\/#\/schema\/person\/919ec47cc1b871b362af05740398033a"},"breadcrumb":{"@id":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.scconline.com\/blog\/post\/2020\/03\/25\/covid-19-nationwide-lockdown-additional-categories-of-essential-goods-and-services-exempted-under-disaster-management-act\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scconline.com\/blog\/"},{"@type":"ListItem","position":2,"name":"COVID-19 | Nationwide lockdown| Additional categories of essential goods and services exempted under Disaster Management Act"}]},{"@type":"WebSite","@id":"https:\/\/www.scconline.com\/blog\/#website","url":"https:\/\/www.scconline.com\/blog\/","name":"SCC Times","description":"Bringing you the Best Analytical Legal News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scconline.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.scconline.com\/blog\/#\/schema\/person\/919ec47cc1b871b362af05740398033a","name":"Bhumika Indulia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/84c1b51748d0297cf12e5a898eccb7bd3eb5f0ab4ae8e275e2e65c4c83f84740?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84c1b51748d0297cf12e5a898eccb7bd3eb5f0ab4ae8e275e2e65c4c83f84740?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84c1b51748d0297cf12e5a898eccb7bd3eb5f0ab4ae8e275e2e65c4c83f84740?s=96&d=mm&r=g","caption":"Bhumika Indulia"},"url":"https:\/\/www.scconline.com\/blog\/post\/author\/editor_1\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/posts\/227554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/users\/8808"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/comments?post=227554"}],"version-history":[{"count":0,"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/posts\/227554\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/media?parent=227554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/categories?post=227554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scconline.com\/blog\/wp-json\/wp\/v2\/tags?post=227554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}